{"id":7808,"date":"2021-12-16T15:33:53","date_gmt":"2021-12-16T14:33:53","guid":{"rendered":"https:\/\/ergosteel-pt.com\/contact\/"},"modified":"2024-05-13T11:35:58","modified_gmt":"2024-05-13T09:35:58","slug":"contact","status":"publish","type":"page","link":"https:\/\/ergosteel-pt.com\/fr\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbCarte\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_map address=\u00a0\u00bbEstrada Vale da Rosa, 2910-845 Set\u00fabal, Portugal\u00a0\u00bb zoom_level=\u00a0\u00bb15&Prime; address_lat=\u00a0\u00bb38.5254488&Prime; address_lng=\u00a0\u00bb-8.8330153&Prime; mouse_wheel=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_width_bottom=\u00a0\u00bb5px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#11B3B9&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_map_pin title=\u00a0\u00bbERGOSTEEL\u00a0\u00bb pin_address=\u00a0\u00bbEstrada Vale da Rosa, 2910-845 Set\u00fabal, Portugal\u00a0\u00bb pin_address_lat=\u00a0\u00bb38.5254488&Prime; pin_address_lng=\u00a0\u00bb-8.8330153&Prime; _builder_version=\u00a0\u00bb4.14.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Aicep Bluebiz Parques<br \/>Estrada Vale da Rosa<br \/>2910-845 SETUBAL<br \/>PORTUGAL<\/p>\n<p>[\/et_pb_map_pin][\/et_pb_map][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbFormulaire\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||110px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||50px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb custom_margin=\u00a0\u00bb0px||10px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Nous contacter<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=\u00a0\u00bb#11B3B9&Prime; divider_weight=\u00a0\u00bb3px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb75px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb14px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Vous avez une question ? Vous souhaitez plus d&rsquo;informations sur nos produits ou notre <br \/>entreprise ? Contactez nous !<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_module=\u00a0\u00bb7801&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(198,198,197,0.3)\u00a0\u00bb custom_padding=\u00a0\u00bb80px|50px|80px|50px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|30px||30px|true|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#11B3B9&Prime; header_3_font_size=\u00a0\u00bb20px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>FORMULAIRE DE CONTACT<\/h3>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_contact_form email=\u00a0\u00bbgeral@ergosteel-pt.com, communication@egicsolutions.com, aureliethomas@ergosteel-pt.com\u00a0\u00bb custom_message=\u00a0\u00bbYou have received a new message from the ERGOSTEEL website contact form :||et_pb_line_break_holder||||et_pb_line_break_holder||||et_pb_line_break_holder||Name : %%Name%%||et_pb_line_break_holder||First name : %%First%%||et_pb_line_break_holder||Company : %%Company%%||et_pb_line_break_holder||Phone : %%Phone%%||et_pb_line_break_holder||Email : %%Email%%||et_pb_line_break_holder||||et_pb_line_break_holder||Message : ||et_pb_line_break_holder||%%Message%%||et_pb_line_break_holder||\u00a0\u00bb success_message=\u00a0\u00bbMerci pour votre message ! Nous vous contacterons d\u00e8s que possible.\u00a0\u00bb submit_button_text=\u00a0\u00bbValider\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb _unique_id=\u00a0\u00bbfd43d50b-8143-4f1c-b45c-e68c85a6aab9&Prime; form_field_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb form_field_text_color=\u00a0\u00bb#1D3557&Prime; form_field_focus_background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb form_field_focus_text_color=\u00a0\u00bb#11B3B9&Prime; title_level=\u00a0\u00bbh3&Prime; title_font=\u00a0\u00bb|300|||||||\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#11B3B9&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bbrgba(29,53,87,0.3)\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb use_spam_service=\u00a0\u00bbon\u00a0\u00bb recaptcha_list=\u00a0\u00bbErgosteelpt|Ergosteelpt-0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_contact_field field_id=\u00a0\u00bbName\u00a0\u00bb field_title=\u00a0\u00bbNom *\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbFirst\u00a0\u00bb field_title=\u00a0\u00bbPr\u00e9nom *\u00a0\u00bb allowed_symbols=\u00a0\u00bbletters\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbCompany\u00a0\u00bb field_title=\u00a0\u00bbEntreprise *\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbPhone\u00a0\u00bb field_title=\u00a0\u00bbT\u00e9l\u00e9phone *\u00a0\u00bb min_length=\u00a0\u00bb8&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbEmail\u00a0\u00bb field_title=\u00a0\u00bbE-mail *\u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessage\u00a0\u00bb field_title=\u00a0\u00bbMessage *\u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><small>* Champs obligatoires<\/small><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#1D3557&Prime; custom_padding=\u00a0\u00bb80px||80px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#11B3B9&Prime; header_3_font_size=\u00a0\u00bb20px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Nos coordonn\u00e9es<\/h3>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb14px\u00a0\u00bb header_4_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_4_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_4_font_size=\u00a0\u00bb14px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb||40px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>ADRESSE<\/h4>\n<p><span>Estrada Vale da Rosa, <br \/>Aicep Bluebiz Parque<br \/><\/span>2910-845 SETUBAL<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb14px\u00a0\u00bb link_font=\u00a0\u00bb|||||||#11B3B9|\u00a0\u00bb link_text_color=\u00a0\u00bb#11B3B9&Prime; header_4_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_4_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_4_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_4_font_size=\u00a0\u00bb14px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>T\u00e9l\u00e9phone &amp; E-mail<\/h4>\n<p>T\u00e9l. +351 265 739 112<br \/>Email. <a href=\"mailto:geral@ergosteel-pt.com\" target=\"_blank\" rel=\"noopener\" title=\"E-mail\">geral@ergosteel-pt.com<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aicep Bluebiz ParquesEstrada Vale da Rosa2910-845 SETUBALPORTUGALNous contacterVous avez une question ? Vous souhaitez plus d&rsquo;informations sur nos produits ou notre entreprise ? Contactez nous !FORMULAIRE DE CONTACT* Champs obligatoiresNos coordonn\u00e9esADRESSE Estrada Vale da Rosa, Aicep Bluebiz Parque2910-845 SETUBALT\u00e9l\u00e9phone &amp; E-mail T\u00e9l. +351 265 739 112Email. geral@ergosteel-pt.com<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-7808","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- ERGOSTEEL<\/title>\n<meta name=\"description\" content=\"Pour toute question ou demande, contactez nous directement gr\u00e2ce \u00e0 notre formulaire de contact.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ergosteel-pt.com\/fr\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- ERGOSTEEL\" \/>\n<meta property=\"og:description\" content=\"Pour toute question ou demande, contactez nous directement gr\u00e2ce \u00e0 notre formulaire de contact.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ergosteel-pt.com\/fr\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"ERGOSTEEL\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-13T09:35:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ergosteel-pt.com\/wp-content\/uploads\/2021\/12\/logo-ergosteel-1024-bleu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/contact\\\/\",\"url\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/contact\\\/\",\"name\":\"- ERGOSTEEL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-12-16T14:33:53+00:00\",\"dateModified\":\"2024-05-13T09:35:58+00:00\",\"description\":\"Pour toute question ou demande, contactez nous directement gr\u00e2ce \u00e0 notre formulaire de contact.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/\",\"name\":\"ERGOSTEEL\",\"description\":\"Computer Furniture\",\"publisher\":{\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/#organization\",\"name\":\"ERGOSTEEL\",\"url\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ergosteel-pt.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo-ergosteel-1024-bleu.png\",\"contentUrl\":\"https:\\\/\\\/ergosteel-pt.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo-ergosteel-1024-bleu.png\",\"width\":1024,\"height\":304,\"caption\":\"ERGOSTEEL\"},\"image\":{\"@id\":\"https:\\\/\\\/ergosteel-pt.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ergosteel\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- ERGOSTEEL","description":"Pour toute question ou demande, contactez nous directement gr\u00e2ce \u00e0 notre formulaire de contact.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ergosteel-pt.com\/fr\/contact\/","og_locale":"fr_FR","og_type":"article","og_title":"- ERGOSTEEL","og_description":"Pour toute question ou demande, contactez nous directement gr\u00e2ce \u00e0 notre formulaire de contact.","og_url":"https:\/\/ergosteel-pt.com\/fr\/contact\/","og_site_name":"ERGOSTEEL","article_modified_time":"2024-05-13T09:35:58+00:00","og_image":[{"width":1024,"height":304,"url":"https:\/\/ergosteel-pt.com\/wp-content\/uploads\/2021\/12\/logo-ergosteel-1024-bleu.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ergosteel-pt.com\/fr\/contact\/","url":"https:\/\/ergosteel-pt.com\/fr\/contact\/","name":"- ERGOSTEEL","isPartOf":{"@id":"https:\/\/ergosteel-pt.com\/fr\/#website"},"datePublished":"2021-12-16T14:33:53+00:00","dateModified":"2024-05-13T09:35:58+00:00","description":"Pour toute question ou demande, contactez nous directement gr\u00e2ce \u00e0 notre formulaire de contact.","breadcrumb":{"@id":"https:\/\/ergosteel-pt.com\/fr\/contact\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ergosteel-pt.com\/fr\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ergosteel-pt.com\/fr\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ergosteel-pt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/ergosteel-pt.com\/fr\/#website","url":"https:\/\/ergosteel-pt.com\/fr\/","name":"ERGOSTEEL","description":"Computer Furniture","publisher":{"@id":"https:\/\/ergosteel-pt.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ergosteel-pt.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ergosteel-pt.com\/fr\/#organization","name":"ERGOSTEEL","url":"https:\/\/ergosteel-pt.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ergosteel-pt.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ergosteel-pt.com\/wp-content\/uploads\/2021\/12\/logo-ergosteel-1024-bleu.png","contentUrl":"https:\/\/ergosteel-pt.com\/wp-content\/uploads\/2021\/12\/logo-ergosteel-1024-bleu.png","width":1024,"height":304,"caption":"ERGOSTEEL"},"image":{"@id":"https:\/\/ergosteel-pt.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/ergosteel\/"]}]}},"_links":{"self":[{"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/pages\/7808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/comments?post=7808"}],"version-history":[{"count":11,"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/pages\/7808\/revisions"}],"predecessor-version":[{"id":10410,"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/pages\/7808\/revisions\/10410"}],"wp:attachment":[{"href":"https:\/\/ergosteel-pt.com\/fr\/wp-json\/wp\/v2\/media?parent=7808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}